{"id":10097,"date":"2018-11-23T20:40:49","date_gmt":"2018-11-24T02:40:49","guid":{"rendered":"https:\/\/visitpatzcuaro.com\/?post_type=citadela-item&#038;p=10097"},"modified":"2026-02-11T12:21:09","modified_gmt":"2026-02-11T18:21:09","slug":"monumento-a-tangaxoan-ii","status":"publish","type":"citadela-item","link":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/item\/monumento-a-tangaxoan-ii\/","title":{"rendered":"Monumento a Tangaxoan II"},"content":{"rendered":"<p style=\"text-align: justify;\" data-path-to-node=\"4\"><b>La memoria de bronce del \u00faltimo Emperador Pur\u00e9pecha<\/b><\/p>\n<p style=\"text-align: justify;\" data-path-to-node=\"5\">Ubicado en la glorieta que lleva su nombre, cerca del Cerro Blanco, este monumento es mucho m\u00e1s que una estatua: es el s\u00edmbolo m\u00e1ximo de la resistencia y la identidad pur\u00e9pecha. Erigido en 1938, durante el auge del nacionalismo impulsado por el general L\u00e1zaro C\u00e1rdenas, honra la vida y el tr\u00e1gico final de <b>Tz\u00edntzicha Tang\u00e1xoan II<\/b>, el \u00faltimo Cazonci (gobernante supremo) del imperio.<\/p>\n<p style=\"text-align: justify;\" data-path-to-node=\"6\"><b>Historia de un Sacrificio<\/b> Tang\u00e1xoan II gobernaba el vasto imperio pur\u00e9pecha a la llegada de los espa\u00f1oles en 1522. Buscando evitar una masacre como la de Tenochtitl\u00e1n, pact\u00f3 una rendici\u00f3n pac\u00edfica(un evento que la tradici\u00f3n sit\u00faa en la actual <b><a class=\"ng-star-inserted\" href=\"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/item\/capilla-de-cristo-el-humilladero\/\" target=\"_blank\" rel=\"noopener\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahgKEwjJm_PI6qGRAxUAAAAAHQAAAAAQowU\">Capilla del Humilladero<\/a><\/b>), pero su destino fue cruel. En 1530, acusado falsamente de conspiraci\u00f3n por el sanguinario Nu\u00f1o de Guzm\u00e1n, fue arrastrado por un caballo, estrangulado y finalmente quemado en la hoguera. Su muerte no fue el fin, sino la semilla de levantamientos posteriores, como el encabezado por su legendaria hija, la princesa <b>Er\u00e9ndira<\/b>.<\/p>\n<p style=\"text-align: justify;\" data-path-to-node=\"7\"><b>Arte y Simbolismo (El Estilo)<\/b> El monumento es obra del escultor <b>Guillermo Ruiz, <\/b>el mismo que levant\u00f3 el <a href=\"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/item\/el-ascenso-en-espiral-estatua-de-morelos-janitzio\/\"><strong>monumento a Morelos<\/strong><\/a> en <strong><a href=\"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/item\/janitzio\/\">Janitzio<\/a>\u00a0<\/strong> y destaca por su estilo <b>Art Dec\u00f3 Indigenista<\/b>, muy propio de la \u00e9poca posrevolucionaria.<\/p>\n<ul style=\"text-align: justify;\" data-path-to-node=\"8\">\n<li>\n<p data-path-to-node=\"8,0,0\"><b>La Estatua:<\/b> De 3 metros de altura, muestra al Cazonci con rasgos ind\u00edgenas prominentes y dignidad real, empu\u00f1ando su bast\u00f3n de mando y <b>mirando fijamente hacia el <a class=\"ng-star-inserted\" href=\"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/loc\/lago-de-patzcuaro\/\" target=\"_blank\" rel=\"noopener\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahgKEwjJm_PI6qGRAxUAAAAAHQAAAAAQiwU\">Lago de P\u00e1tzcuaro<\/a><\/b>, el coraz\u00f3n de sus dominios.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,1,0\"><b>El Pedestal:<\/b> La base de cantera es un libro de historia en bronce. Sus relieves narran tres momentos clave:<\/p>\n<ol start=\"1\" data-path-to-node=\"8,1,1\">\n<li>\n<p data-path-to-node=\"8,1,1,0,0\">El encuentro con Crist\u00f3bal de Olid (1522).<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,1,1,1,0\">El suplicio y muerte en la hoguera (1530).<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,1,1,2,0\">El \u00e1rbol geneal\u00f3gico de los reyes tarascos.<\/p>\n<\/li>\n<\/ol>\n<\/li>\n<\/ul>\n<blockquote data-path-to-node=\"9\">\n<p style=\"text-align: justify;\" data-path-to-node=\"9,0\"><b>\ud83d\udcc5 Evento Anual: 14 de Febrero<\/b> Mientras el mundo celebra el amor, P\u00e1tzcuaro recuerda a su rey. Cada <a href=\"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/item\/aniversario-luctuoso-de-tangaxoan-ii\/\"><b>14 de febrero<\/b><\/a> (aniversario de su ejecuci\u00f3n), se realiza una ceremonia solemne con danzas, m\u00fasica y ofrendas. El acto incluye un recorrido simb\u00f3lico que va desde este monumento hasta el <b><a class=\"ng-star-inserted\" href=\"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/item\/palacio-de-huitizimengari\/\" target=\"_blank\" rel=\"noopener\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahgKEwjJm_PI6qGRAxUAAAAAHQAAAAAQjAU\">Palacio de Huitzim\u00e9ngari<\/a><\/b> en la <a href=\"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/item\/plaza-vasco-de-quiroga\/\">Plaza Grande<\/a>, conectando as\u00ed al padre (el \u00faltimo emperador) con la casa de su hijo (Antonio de Huitzim\u00e9ngari), en un gesto de continuidad hist\u00f3rica.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>La memoria de bronce del \u00faltimo Emperador Pur\u00e9pecha Ubicado en la glorieta que lleva su nombre, cerca del Cerro Blanco, este monumento es mucho m\u00e1s que una estatua: es el s\u00edmbolo m\u00e1ximo de la resistencia y la identidad pur\u00e9pecha. Erigido en 1938, durante el auge del nacionalismo impulsado por el general L\u00e1zaro C\u00e1rdenas, honra la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10098,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","citadela-item-category":[397],"citadela-item-location":[392],"class_list":["post-10097","citadela-item","type-citadela-item","status-publish","has-post-thumbnail","hentry","citadela-item-category-plazas-y-mas","citadela-item-location-patzcuaro"],"_links":{"self":[{"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/citadela-item\/10097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/citadela-item"}],"about":[{"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/types\/citadela-item"}],"author":[{"embeddable":true,"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/comments?post=10097"}],"version-history":[{"count":0,"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/citadela-item\/10097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/media\/10098"}],"wp:attachment":[{"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/media?parent=10097"}],"wp:term":[{"taxonomy":"citadela-item-category","embeddable":true,"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/citadela-item-category?post=10097"},{"taxonomy":"citadela-item-location","embeddable":true,"href":"https:\/\/villapatzcuaro.com\/visitpatzcuaro\/wp-json\/wp\/v2\/citadela-item-location?post=10097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}